{"id":4178,"date":"2022-09-17T23:25:15","date_gmt":"2022-09-17T23:25:15","guid":{"rendered":"https:\/\/evidencia-pe.com\/blog\/?p=4178"},"modified":"2022-09-21T22:57:44","modified_gmt":"2022-09-21T22:57:44","slug":"expectativas-e-inversion-en-un-contexto-de-incertidumbre","status":"publish","type":"post","link":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/","title":{"rendered":"Expectativas e Inversion en un Contexto de Incertidumbre"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"4178\" class=\"elementor elementor-4178\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28760be6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28760be6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17905634\" data-id=\"17905634\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd27ad8 elementor-invisible elementor-widget elementor-widget-avo-title\" data-id=\"bd27ad8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"avo-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t \r\n<div class=\"avo-title style-1 \">\r\n\r\n\t    <div class=\"animate sub-title\">\r\n        <h6>ARTICULO DE OPINION<\/h6>\r\n        <span><\/span>\r\n        <span><\/span>\r\n        <span><\/span>\r\n    <\/div>\r\n    \r\n        <h3 class=\"main-title \" data-splitting>EXPECTATIVAS E INVERSI\u00d3N EN UN CONTEXTO DE INCERTIDUMBRE<\/h3>\r\n        <p class=\" txt\" data-splitting>El Descontento social, el ruido pol\u00edtico local, la falta de perfiles especializados en puestos clave y las fricciones entre Ejecutivo y Legislativo golpearon las expectativas empresariales hasta situarlas a niveles similares a los de la crisis del 2008<\/p>\r\n\t<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b208480 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b208480\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-71f3af8\" data-id=\"71f3af8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ce3df3 elementor-widget elementor-widget-text-editor\" data-id=\"4ce3df3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 14-09-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<h2 style=\"text-align: left;\" align=\"justify\">\u00bfQu\u00e9 influye en las decisiones o comportamientos de los agentes econ\u00f3micos?<\/h2><p style=\"text-align: left;\" align=\"justify\">Existe una amplia literatura que aborda esta ambiciosa interrogante, sin embargo, la mayor\u00eda concuerda que son las expectativas los principales motores de nuestras decisiones. Una manera intuitiva de comprender la econom\u00eda y las expectativas es mediante el estudio de tres variables importantes: la inversi\u00f3n, el empleo y el consumo. Las empresas, mediante sus decisiones de inversi\u00f3n, aumentan su capacidad productiva y fomentan la demanda de puestos laborales (empleo). Asimismo, los mayores niveles de empleo permiten dotar de ingresos a m\u00e1s familias posibilit\u00e1ndoles incrementar sus niveles de consumo.<\/p><h2 style=\"text-align: left;\" align=\"justify\">\u00bfSiempre se cumple la relaci\u00f3n virtuosa entre inversi\u00f3n, empleo y consumo?<\/h2><p style=\"text-align: left;\" align=\"justify\">Un repaso r\u00e1pido de las estad\u00edsticas peruanas nos muestra que la inversi\u00f3n de un trimestre anterior y el empleo actual presentan una correlaci\u00f3n positiva de 0.82[1]. Por su parte, el empleo y el consumo registran una correlaci\u00f3n de 0.72[2]. De lo anterior, podemos inferir que las tres variables presentan un comovimiento conjunto positivo. Del mismo modo, el consumo de car\u00e1cter privado representa aproximadamente el 65% del PBI peruano (MEF, 2021), por lo tanto, la relaci\u00f3n descrita anteriormente explica gran parte de la actividad econ\u00f3mica local.<\/p><p align=\"justify\">\u00a0<\/p><p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4225 size-full\" src=\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/g1.png\" alt=\"\" width=\"456\" height=\"285\" \/><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9b44c66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9b44c66\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-451367b\" data-id=\"451367b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-397b1ba elementor-widget elementor-widget-text-editor\" data-id=\"397b1ba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h6><span style=\"font-size: small;\">Fuente: BCRP y Ministerio de Trabajo (MIT), elaboraci\u00f3n propia<\/span><\/h6><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4226 size-full\" src=\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/g2.png\" alt=\"\" width=\"481\" height=\"289\" \/><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ce8b9b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ce8b9b1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2563034\" data-id=\"2563034\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd46faa elementor-widget elementor-widget-text-editor\" data-id=\"bd46faa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h6><span style=\"font-size: small;\">Fuente: BCRP y Ministerio de Trabajo (MIT), elaboraci\u00f3n propia<\/span><\/h6>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e35a7c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e35a7c7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a2e45a5\" data-id=\"a2e45a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4c540e elementor-widget elementor-widget-text-editor\" data-id=\"f4c540e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>\u00bfQu\u00e9 es lo que determina la inversi\u00f3n?<\/h2><p align=\"justify\">Los agentes econ\u00f3micos encargados de las decisiones de inversi\u00f3n son, principalmente, las empresas, por ende, son las expectativas empresariales las que podr\u00edan darnos una imagen \u201cadelantada\u201d de la inversi\u00f3n, puesto que los empresarios poseen informaci\u00f3n m\u00e1s amplia acerca de la actividad: el volumen de ventas diarias, el n\u00famero de pedidos (indicador de la demanda futura) o los proyectos de inversiones pr\u00f3ximos a ejecutar. Del mismo modo, por cada punto adicional de las expectativas, la inversi\u00f3n privada aumenta en 1.7% (Castilla, 2020).<\/p><p align=\"justify\">El Banco Central de Reserva (BCRP) elabora mensualmente una encuesta a una muestra representativa de empresas de los diversos sectores econ\u00f3micos del pa\u00eds acerca de la situaci\u00f3n actual del negocio, sus proyectos de inversi\u00f3n y los planes de contrataci\u00f3n de personal. Asimismo, construye un \u00edndice de difusi\u00f3n en base a las respuestas de quienes tienen una perspectiva positiva y negativa (BCRP, 2011). El \u00edndice est\u00e1 acotado entre 0 y 100 y se considera \u201coptimista\u201d si su valor es mayor a 50 y \u201cpesimista\u201d si se registra por debajo de dicho valor. Por otro lado, el \u00edndice de expectativas del trimestre inmediato anterior registra una correlaci\u00f3n de 0.78[3] con la inversi\u00f3n privada actual o, dicho de otra forma, las expectativas son un indicador adelantado de la inversi\u00f3n privada.<\/p><p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4227 size-full\" src=\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/g3.png\" alt=\"\" width=\"481\" height=\"289\" \/><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-745689b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"745689b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c56de8\" data-id=\"1c56de8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a84fa18 elementor-widget elementor-widget-text-editor\" data-id=\"a84fa18\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h6><span style=\"font-size: small;\">Fuente: BCRP, elaboraci\u00f3n propia<\/span><\/h6>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f00a06 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f00a06\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-796c8aa\" data-id=\"796c8aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a5d8a15 elementor-widget elementor-widget-text-editor\" data-id=\"a5d8a15\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2>\u00bfC\u00f3mo van las expectativas en el panorama actual?<\/h2><p align=\"justify\">Per\u00fa es considerado una econom\u00eda peque\u00f1a y abierta, por lo tanto, su desempe\u00f1o econ\u00f3mico depender\u00e1 del dinamismo del sector externo; espec\u00edficamente, de los precios de sus principales productos de exportaci\u00f3n como el cobre, oro y zinc. Una primera y correcta intuici\u00f3n nos llevar\u00eda a concluir que en tiempos en que los precios de commodities son altos, la econom\u00eda -junto con sus expectativas- tender\u00e1 a elevarse como sucedi\u00f3 en el 2011 donde el boom en el precio del cobre situ\u00f3 nuestras expectativas en 73 puntos y la inversi\u00f3n privada creci\u00f3 30.3% en el primer trimestre de dicho a\u00f1o.<\/p><p align=\"justify\">Por otro lado, tambi\u00e9n es plausible inferir que en tiempos de baja cotizaci\u00f3n de los metales de exportaci\u00f3n o menores tasas de crecimiento de nuestros principales socios comerciales (EE.UU y China), se deteriorar\u00edan las expectativas empresariales, con la consiguiente reducci\u00f3n en los niveles de inversi\u00f3n. Lo anterior se evidenci\u00f3 tanto en la crisis del 2008 como en la pandemia del COVID-19, momentos en los cuales las expectativas tocaron piso, rebaj\u00e1ndose a niveles de 35.3 y 17.4 puntos, respectivamente. En la misma l\u00ednea, la inversi\u00f3n privada se contrajo durante el segundo trimestre del 2008 en un 16% % y en un 57% en tercer trimestre del 2020 (BCRP).<\/p><p align=\"justify\">Los resultados del primer semestre del 2022 no fueron los m\u00e1s favorables: el conflicto b\u00e9lico entre Rusia y Ucrania, los persistentes altos niveles de inflaci\u00f3n alrededor del mundo y el endurecimiento de las condiciones financieras recortaron las previsiones de crecimiento a nivel mundial (2022: 3.2%, 2023: 2.9%). Del mismo modo, el descontento social, el constante ruido pol\u00edtico a nivel local, la falta de perfiles especializados en puestos p\u00fablicos claves y las continuas fricciones entre el Ejecutivo y el Legislativo golpearon las expectativas empresariales hasta situarlas a niveles similares a los de la crisis del 2008 (T1-2022: 35 pts.), cuando la inversi\u00f3n toc\u00f3 terreno negativo.<\/p><p align=\"justify\">Recordemos que entidades como el BCRP y el MEF proyectan un crecimiento nulo de la inversi\u00f3n privada para el presente a\u00f1o. Sin embargo, las expectativas vienen registr\u00e1ndose en territorio pesimista por quince meses consecutivos y situ\u00e1ndose en niveles m\u00ednimos, lo que podr\u00eda desencadenar previsiones a la baja de inversi\u00f3n, empleo, consumo y PBI. El posible panorama de menor crecimiento jugar\u00eda en contra a partir del 2023 y los pr\u00f3ximos a\u00f1os, dado que no se generar\u00edan los puestos de trabajo necesarios para sostener los actuales niveles de consumo y bienestar y adem\u00e1s incentivar\u00eda a mayores tasas de ahorro y baja actividad comercial.<\/p><h2>\u00bfQu\u00e9 se deber\u00eda hacer?<\/h2><p align=\"justify\">Las previsiones de crecimiento econ\u00f3mico peruano para el pr\u00f3ximo a\u00f1o rondan el 2.8% desde una previsi\u00f3n inicial de 4.0% a inicios de a\u00f1o (MEF, 2022). En este contexto, el fisco deber\u00e1 implementar medidas enfocadas a la recuperaci\u00f3n de la confianza empresarial, debido a que un aumento en 10 puntos de las expectativas impulsar\u00eda en un 0.8% al PBI, mediante la relaci\u00f3n entre inversi\u00f3n, empleo y consumo [4]. La percepci\u00f3n sobre la estabilidad de las reglas de juego y la capacidad de la administraci\u00f3n p\u00fablica para generar un entorno favorable para los negocios, ser\u00e1n los principales retos de la pol\u00edtica p\u00fablica en el corto y mediano plazo.<\/p><p align=\"justify\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4228 size-full\" src=\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/g4.png\" alt=\"\" width=\"481\" height=\"289\" \/><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-256d3a3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"256d3a3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e3507d8\" data-id=\"e3507d8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4aade72 elementor-widget elementor-widget-text-editor\" data-id=\"4aade72\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<hr \/><h6><span style=\"font-size: small;\">[1]<\/span><span style=\"font-size: small;\"> Correlaci\u00f3n estimada entre el primer trimestre del 2004 y tercer trimestre del 2019<\/span><\/h6><h6><span style=\"font-size: small;\">[2]<\/span><span style=\"font-size: small;\"> Correlaci\u00f3n estimada entre el primer trimestre del 2004 y tercer trimestre del 2019<\/span><\/h6><h6><span style=\"font-size: small;\">[3]<\/span> <span style=\"font-size: small;\">Correlaci\u00f3n estimada entre el primer trimestre del 2004 y tercer trimestre del 2019<\/span><\/h6><h6><span style=\"font-size: small;\">[4] Estimaciones propias mediante un modelo SVAR entre el primer trimestre del 2004 y tercer trimestre del 2019<\/span><\/h6><hr \/><p>Referencias<\/p><p>BCR. (s.f.). <em>Gu\u00eda metodol\u00f3gica de la Nota Semanal.<\/em> Lima: BCR.<\/p><p>BofA. (2022). <em>Global Economic Weekly.<\/em> Bank of Amercia.<\/p><p>IMF. (2022). <em>World Economic Outlook update.<\/em> United States.<\/p><p>Jim\u00e9nez, J. M. (2007). <em>An\u00e1lisis cuantitativo de la coyuntura econ\u00f3mica &#8211; Una aplicaci\u00f3n de la representaci\u00f3n en espacio de estados de series temporales m\u00faltiples<\/em>. Cuenca: Ediciones de la Universidad de Castilla-La Mancha.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-51128b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"51128b3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e745e74\" data-id=\"e745e74\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>ARTICULO DE OPINION EXPECTATIVAS E INVERSI\u00d3N EN UN CONTEXTO DE INCERTIDUMBRE El Descontento social, el ruido pol\u00edtico local, la falta de perfiles especializados en puestos clave y las fricciones entre Ejecutivo y Legislativo golpearon las expectativas empresariales hasta situarlas a niveles similares a los de la crisis del 2008 \u00bfQu\u00e9 influye en las decisiones o comportamientos de los agentes econ\u00f3micos? &hellip;<\/p>\n","protected":false},"author":14,"featured_media":4154,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[49],"tags":[53,71],"ppma_author":[32],"class_list":["post-4178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-opinion","tag-economia","tag-peru"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Expectativas e Inversion en un Contexto de Incertidumbre - Evidencia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expectativas e Inversion en un Contexto de Incertidumbre - Evidencia\" \/>\n<meta property=\"og:description\" content=\"ARTICULO DE OPINION EXPECTATIVAS E INVERSI\u00d3N EN UN CONTEXTO DE INCERTIDUMBRE El Descontento social, el ruido pol\u00edtico local, la falta de perfiles especializados en puestos clave y las fricciones entre Ejecutivo y Legislativo golpearon las expectativas empresariales hasta situarlas a niveles similares a los de la crisis del 2008 \u00bfQu\u00e9 influye en las decisiones o comportamientos de los agentes econ\u00f3micos? &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/\" \/>\n<meta property=\"og:site_name\" content=\"Evidencia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/evidencia.pe\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-17T23:25:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-21T22:57:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/expectativas-inversion.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Daniel Flores\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Evidencia_pe\" \/>\n<meta name=\"twitter:site\" content=\"@Evidencia_pe\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Flores\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/\"},\"author\":{\"name\":\"Daniel Flores\",\"@id\":\"https:\/\/evidencia-pe.com\/blog\/#\/schema\/person\/903ad93ac9e4fdcddb545908879e473b\"},\"headline\":\"Expectativas e Inversion en un Contexto de Incertidumbre\",\"datePublished\":\"2022-09-17T23:25:15+00:00\",\"dateModified\":\"2022-09-21T22:57:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/\"},\"wordCount\":1193,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/evidencia-pe.com\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/expectativas-inversion.webp\",\"keywords\":[\"Econom\u00eda\",\"Per\u00fa\"],\"articleSection\":[\"Art\u00edculo de Opini\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/\",\"url\":\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/\",\"name\":\"Expectativas e Inversion en un Contexto de Incertidumbre - Evidencia\",\"isPartOf\":{\"@id\":\"https:\/\/evidencia-pe.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/expectativas-inversion.webp\",\"datePublished\":\"2022-09-17T23:25:15+00:00\",\"dateModified\":\"2022-09-21T22:57:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#primaryimage\",\"url\":\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/expectativas-inversion.webp\",\"contentUrl\":\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/expectativas-inversion.webp\",\"width\":1080,\"height\":1080,\"caption\":\"Flyer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/evidencia-pe.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expectativas e Inversion en un Contexto de Incertidumbre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/evidencia-pe.com\/blog\/#website\",\"url\":\"https:\/\/evidencia-pe.com\/blog\/\",\"name\":\"Evidencia\",\"description\":\"Observatorio de pol\u00edticas p\u00fablicas\",\"publisher\":{\"@id\":\"https:\/\/evidencia-pe.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/evidencia-pe.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/evidencia-pe.com\/blog\/#organization\",\"name\":\"Evidencia\",\"url\":\"https:\/\/evidencia-pe.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/evidencia-pe.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2021\/07\/logo-new.png\",\"contentUrl\":\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2021\/07\/logo-new.png\",\"width\":1799,\"height\":2044,\"caption\":\"Evidencia\"},\"image\":{\"@id\":\"https:\/\/evidencia-pe.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/evidencia.pe\/\",\"https:\/\/x.com\/Evidencia_pe\",\"https:\/\/www.instagram.com\/evidencia_pe\/\",\"https:\/\/www.linkedin.com\/company\/evidencia-pe\/\",\"https:\/\/www.youtube.com\/channel\/UCrTD_hhcBfmY3B-ZgLF5xRg\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/evidencia-pe.com\/blog\/#\/schema\/person\/903ad93ac9e4fdcddb545908879e473b\",\"name\":\"Daniel Flores\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/evidencia-pe.com\/blog\/#\/schema\/person\/image\/8a48926da03ecd02faea5d6800d9d046\",\"url\":\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/daniel_flores.webp\",\"contentUrl\":\"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/daniel_flores.webp\",\"caption\":\"Daniel Flores\"},\"url\":\"https:\/\/evidencia-pe.com\/blog\/author\/danielflores\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expectativas e Inversion en un Contexto de Incertidumbre - Evidencia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/","og_locale":"es_ES","og_type":"article","og_title":"Expectativas e Inversion en un Contexto de Incertidumbre - Evidencia","og_description":"ARTICULO DE OPINION EXPECTATIVAS E INVERSI\u00d3N EN UN CONTEXTO DE INCERTIDUMBRE El Descontento social, el ruido pol\u00edtico local, la falta de perfiles especializados en puestos clave y las fricciones entre Ejecutivo y Legislativo golpearon las expectativas empresariales hasta situarlas a niveles similares a los de la crisis del 2008 \u00bfQu\u00e9 influye en las decisiones o comportamientos de los agentes econ\u00f3micos? &hellip;","og_url":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/","og_site_name":"Evidencia","article_publisher":"https:\/\/www.facebook.com\/evidencia.pe\/","article_published_time":"2022-09-17T23:25:15+00:00","article_modified_time":"2022-09-21T22:57:44+00:00","og_image":[{"width":1080,"height":1080,"url":"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/expectativas-inversion.webp","type":"image\/webp"}],"author":"Daniel Flores","twitter_card":"summary_large_image","twitter_creator":"@Evidencia_pe","twitter_site":"@Evidencia_pe","twitter_misc":{"Escrito por":"Daniel Flores","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#article","isPartOf":{"@id":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/"},"author":{"name":"Daniel Flores","@id":"https:\/\/evidencia-pe.com\/blog\/#\/schema\/person\/903ad93ac9e4fdcddb545908879e473b"},"headline":"Expectativas e Inversion en un Contexto de Incertidumbre","datePublished":"2022-09-17T23:25:15+00:00","dateModified":"2022-09-21T22:57:44+00:00","mainEntityOfPage":{"@id":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/"},"wordCount":1193,"commentCount":0,"publisher":{"@id":"https:\/\/evidencia-pe.com\/blog\/#organization"},"image":{"@id":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#primaryimage"},"thumbnailUrl":"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/expectativas-inversion.webp","keywords":["Econom\u00eda","Per\u00fa"],"articleSection":["Art\u00edculo de Opini\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/","url":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/","name":"Expectativas e Inversion en un Contexto de Incertidumbre - Evidencia","isPartOf":{"@id":"https:\/\/evidencia-pe.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#primaryimage"},"image":{"@id":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#primaryimage"},"thumbnailUrl":"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/expectativas-inversion.webp","datePublished":"2022-09-17T23:25:15+00:00","dateModified":"2022-09-21T22:57:44+00:00","breadcrumb":{"@id":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#primaryimage","url":"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/expectativas-inversion.webp","contentUrl":"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/expectativas-inversion.webp","width":1080,"height":1080,"caption":"Flyer"},{"@type":"BreadcrumbList","@id":"https:\/\/evidencia-pe.com\/blog\/2022\/09\/expectativas-e-inversion-en-un-contexto-de-incertidumbre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/evidencia-pe.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Expectativas e Inversion en un Contexto de Incertidumbre"}]},{"@type":"WebSite","@id":"https:\/\/evidencia-pe.com\/blog\/#website","url":"https:\/\/evidencia-pe.com\/blog\/","name":"Evidencia","description":"Observatorio de pol\u00edticas p\u00fablicas","publisher":{"@id":"https:\/\/evidencia-pe.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/evidencia-pe.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/evidencia-pe.com\/blog\/#organization","name":"Evidencia","url":"https:\/\/evidencia-pe.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/evidencia-pe.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2021\/07\/logo-new.png","contentUrl":"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2021\/07\/logo-new.png","width":1799,"height":2044,"caption":"Evidencia"},"image":{"@id":"https:\/\/evidencia-pe.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/evidencia.pe\/","https:\/\/x.com\/Evidencia_pe","https:\/\/www.instagram.com\/evidencia_pe\/","https:\/\/www.linkedin.com\/company\/evidencia-pe\/","https:\/\/www.youtube.com\/channel\/UCrTD_hhcBfmY3B-ZgLF5xRg"]},{"@type":"Person","@id":"https:\/\/evidencia-pe.com\/blog\/#\/schema\/person\/903ad93ac9e4fdcddb545908879e473b","name":"Daniel Flores","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/evidencia-pe.com\/blog\/#\/schema\/person\/image\/8a48926da03ecd02faea5d6800d9d046","url":"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/daniel_flores.webp","contentUrl":"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/daniel_flores.webp","caption":"Daniel Flores"},"url":"https:\/\/evidencia-pe.com\/blog\/author\/danielflores\/"}]}},"authors":[{"term_id":32,"user_id":14,"is_guest":0,"slug":"danielflores","display_name":"Daniel Flores","avatar_url":{"url":"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/daniel_flores.webp","url2x":"https:\/\/evidencia-pe.com\/blog\/wp-content\/uploads\/2022\/09\/daniel_flores.webp"},"author_category":"","user_url":"","last_name":"Flores","first_name":"Daniel","job_title":"","description":"Estudiante de Econom\u00eda en la Universidad Nacional Mayor de San Marcos. Miembro del C\u00edrculo de Formaci\u00f3n Macroecon\u00f3mica de la UNI. Actual praticante preprofesional de Reseacrh en el \u00e1rea de Mercado de Capitales en Interbank."}],"_links":{"self":[{"href":"https:\/\/evidencia-pe.com\/blog\/wp-json\/wp\/v2\/posts\/4178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/evidencia-pe.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/evidencia-pe.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/evidencia-pe.com\/blog\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/evidencia-pe.com\/blog\/wp-json\/wp\/v2\/comments?post=4178"}],"version-history":[{"count":38,"href":"https:\/\/evidencia-pe.com\/blog\/wp-json\/wp\/v2\/posts\/4178\/revisions"}],"predecessor-version":[{"id":4231,"href":"https:\/\/evidencia-pe.com\/blog\/wp-json\/wp\/v2\/posts\/4178\/revisions\/4231"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/evidencia-pe.com\/blog\/wp-json\/wp\/v2\/media\/4154"}],"wp:attachment":[{"href":"https:\/\/evidencia-pe.com\/blog\/wp-json\/wp\/v2\/media?parent=4178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/evidencia-pe.com\/blog\/wp-json\/wp\/v2\/categories?post=4178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/evidencia-pe.com\/blog\/wp-json\/wp\/v2\/tags?post=4178"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/evidencia-pe.com\/blog\/wp-json\/wp\/v2\/ppma_author?post=4178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}